{"id":17886,"date":"2015-09-16T17:18:13","date_gmt":"2015-09-16T15:18:13","guid":{"rendered":"https:\/\/cogolandia.com\/?p=17886"},"modified":"2023-08-22T10:57:45","modified_gmt":"2023-08-22T10:57:45","slug":"por-un-error-colorado-sufre-durante-un-dia-la-exencion-de-impuestos-sobre-la-marihuana","status":"publish","type":"post","link":"https:\/\/cogolandia.com\/blog\/impuestos-marihuana\/por-un-error-colorado-sufre-durante-un-dia-la-exencion-de-impuestos-sobre-la-marihuana\/","title":{"rendered":"POR UN ERROR, COLORADO SUFRE DURANTE UN DIA LA EXENCI\u00d3N DE IMPUESTOS SOBRE LA MARIHUANA"},"content":{"rendered":"<p>Un error contable en Colorado beneficiar\u00e1 a los consumidores de marihuana el mi\u00e9rcoles, cuando una peculiaridad de la ley impositiva estatal obligue al estado a suspender la mayor\u00eda de los impuestos sobre el cannabis para consumo recreativo. El feriado impositivo significa que Colorado no recaudar\u00e1 el impuesto del 10% sobre las ventas de la yerba. Asimismo queda suspendido un impuesto del 15% a los cultivadores de marihuana.<\/p>\n<h2>Un error contable beneficia a consumidores de marihuana en Colorado<\/h2>\n<p>Esta exenci\u00f3n se debe a que Colorado subestim\u00f3 las recaudaciones impositivas globales del a\u00f1o pasado. Bajo la constituci\u00f3n estatal, este error contable obliga a suspender cualquier impuesto nuevo, en este caso los impuestos sobre la marihuana para consumo recreativo que los votantes aprobaron en 2013.<\/p>\n<p>Los vendedores minoristas esperan multitudes, a las que atraen con jugosas ofertas. El estado no ha calculado cu\u00e1ntos compradores podr\u00edan acudir. Los impuestos volver\u00e1n a ser del 25% el jueves. El feriado impositivo del mi\u00e9rcoles llega un d\u00eda despu\u00e9s de que Colorado cerr\u00f3 las cuentas para el a\u00f1o fiscal que finaliz\u00f3 en junio, el primero en que los adultos mayores de 21 a\u00f1os pudieron comprar legalmente marihuana y alcohol.<\/p>\n<p>La recaudaci\u00f3n del impuesto sobre el consumo de alcohol aument\u00f3 2,4% a 42 millones de d\u00f3lares. Los impuestos sobre la marihuana recaudaron unos 70 millones de d\u00f3lares. Las cifras no incluyeron los impuestos del 2,9% sobre las ventas. Las bebidas alcoh\u00f3licas probablemente recaudan m\u00e1s impuestos que la marihuana, aunque el estado no lleva las cuentas del dinero recaudado por el et\u00edlico en cuentas generales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un error contable en Colorado beneficiar\u00e1 a los consumidores de marihuana el mi\u00e9rcoles, cuando una peculiaridad de la ley impositiva estatal obligue al estado a suspender la mayor\u00eda de los impuestos sobre el cannabis para consumo recreativo. El feriado impositivo significa que Colorado no recaudar\u00e1 el impuesto del 10% sobre las ventas de la yerba. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":67574,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-17886","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-impuestos-marihuana"],"_links":{"self":[{"href":"https:\/\/cogolandia.com\/blog\/wp-json\/wp\/v2\/posts\/17886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cogolandia.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cogolandia.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cogolandia.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cogolandia.com\/blog\/wp-json\/wp\/v2\/comments?post=17886"}],"version-history":[{"count":1,"href":"https:\/\/cogolandia.com\/blog\/wp-json\/wp\/v2\/posts\/17886\/revisions"}],"predecessor-version":[{"id":67575,"href":"https:\/\/cogolandia.com\/blog\/wp-json\/wp\/v2\/posts\/17886\/revisions\/67575"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cogolandia.com\/blog\/wp-json\/wp\/v2\/media\/67574"}],"wp:attachment":[{"href":"https:\/\/cogolandia.com\/blog\/wp-json\/wp\/v2\/media?parent=17886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cogolandia.com\/blog\/wp-json\/wp\/v2\/categories?post=17886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cogolandia.com\/blog\/wp-json\/wp\/v2\/tags?post=17886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}