{"id":20086,"date":"2016-07-13T11:29:11","date_gmt":"2016-07-13T09:29:11","guid":{"rendered":"https:\/\/cogolandia.com\/?p=20086"},"modified":"2016-07-13T11:29:11","modified_gmt":"2016-07-13T09:29:11","slug":"cultivar-marihuana-en-verano-2","status":"publish","type":"post","link":"https:\/\/cogolandia.com\/blog\/cannabis\/cultivar-marihuana-en-verano-2\/","title":{"rendered":"Cultivar marihuana en verano"},"content":{"rendered":"<p>El verano no es bienvenido por mucha gente, y menos por los cultivadores de marihuana en interior. Cultivar marihuana en verano es toda una odisea, ya que es el per\u00edodo\u00a0<strong>m\u00e1s delicado para las plantas.\u00a0<\/strong>Un cultivo indoor es todo un reto para cualquier cultivador. El calor de las l\u00e1mparas y de los aparatos, unidos a las temperaturas del exterior, hace mucho m\u00e1s dif\u00edcil conservar una temperatura \u00f3ptima para nuestro cultivo.<\/p>\n<p>En estos casos, muchos cultivadores dejan de cultivar. Otros contin\u00faan a pesar de las consecuencias que puedan surgir.<\/p>\n<p>Algunos de los problemas que podemos encontrar si cultivamos en verano son el <strong>calor<\/strong>, la <strong>humedad<\/strong> y las <strong>plagas de insectos<\/strong> u <strong>hongos<\/strong>.<\/p>\n<p>En este post os vamos a detallar unos consejos y soluciones para mantener una buena temperatura en la zona de cultivo.<\/p>\n<h2><strong>El CO2 en nuestro cuarto de cultivo para cultivar marihuana en verano<\/strong><\/h2>\n<p>Si hemos decidido cultivar marihuana en verano y con altas temperaturas, lo primero que debemos saber es que <strong>la temperatura ideal para las plantas se eleva cuando aumenta el nivel de CO2 en el aire<\/strong>.<\/p>\n<p>Sabemos que toda planta necesita CO2 por el d\u00eda, ya que por la noche lo libera y absorbe ox\u00edgeno.<\/p>\n<p>Cuando encendemos las l\u00e1mparas de nuestro cuarto de cultivo, la temperatura aumenta considerablemente. Por ello, necesitamos <strong>renovar el aire del interior<\/strong> para que no se sobrecaliente el ambiente.<\/p>\n<p>La temperatura ideal para nuestra planta <strong>es de 24\u00baC<\/strong>. \u00bfC\u00f3mo sabemos esto? Pues porque es cuando la concentraci\u00f3n de CO2 es normal en la atm\u00f3sfera. Entonces lo que haremos ser\u00e1 ir <strong>renovando el aire<\/strong> de nuestro indoor para que no se caliente.<\/p>\n<p>Es cierto que aunque 24\u00baC es la temperatura ideal, las plantas pueden soportar perfectamente temperaturas de entre 25 y 30\u00baC. Sin embargo, <strong>cuando superan los 31\u00baC<\/strong> es cuando empiezan a gastar mucha energ\u00eda para combatir el calor. Esto es lo que hace reducir la producci\u00f3n y que el resultado no sea el esperado.<\/p>\n<p>Si, por el contrario, tienes que cultivar marihuana en verano y a temperaturas altas, es importante seguir una serie de consejos para que las plantas sobrevivan. Lo primero que debes hacer para que las plantas se refresquen es <strong>aumentar el n\u00famero de riegos<\/strong>. A mayor calor, m\u00e1s agua evaporar\u00e1n por sus poros.<\/p>\n<p style=\"text-align: left;\"><a href=\"https:\/\/cogolandia.com\/wp-content\/uploads\/2016\/07\/cultivar-marihuana-en-verano.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\" wp-image-20087 alignleft\" src=\"https:\/\/cogolandia.com\/wp-content\/uploads\/2016\/07\/cultivar-marihuana-en-verano.jpg\" alt=\"cultivar marihuana en verano\" width=\"486\" height=\"324\" srcset=\"https:\/\/cogolandia.com\/blog\/wp-content\/uploads\/2016\/07\/cultivar-marihuana-en-verano.jpg 450w, https:\/\/cogolandia.com\/blog\/wp-content\/uploads\/2016\/07\/cultivar-marihuana-en-verano-300x200.jpg 300w\" sizes=\"(max-width: 486px) 100vw, 486px\" \/><\/a><\/p>\n<h2><strong>Controlar la humedad<\/strong><\/h2>\n<p>Hay d\u00edas en los que las temperaturas son mucho m\u00e1s altas de lo deseado.<\/p>\n<p>Tambi\u00e9n es cierto que manteniendo una humedad baja en el ambiente, evitaremos la aparici\u00f3n de plagas. Sin embargo, la falta de humedad har\u00e1 que las plantas <strong>transpiren m\u00e1s de lo deseado<\/strong>.<\/p>\n<p>Lo ideal es que el nivel de humedad oscile entre el <strong>50%.<\/strong> Ni muy alto, ni demasiado bajo. Consulta nuestros <a href=\"https:\/\/cogolandia.com\/producto\/deshumidifcador-mini-vdl\/\">\u00a0deshumidificadores<\/a>.<\/p>\n<p>Una buena soluci\u00f3n es utilizar <a href=\"https:\/\/cogolandia.com\/producto\/ventilador-de-pinza-cyclone\/\">ventiladores<\/a>, que logran que no haya calor y ayuda a que nuestras plantas transpiren.<\/p>\n<h2><\/h2>\n<h2><strong>Disminuir la temperatura del indoor<\/strong><\/h2>\n<p>La temperatura de la zona de cultivo aumenta con los aparatos el\u00e9ctricos.<\/p>\n<p>No es necesario tenerlos todos dentro del cuarto. Podemos optar por dejar solo las <strong>bombillas y el ventilador<\/strong>. Los otros aparatos (como los balastros) los dejaremos fuera para mantener la temperatura interior.<\/p>\n<p>Adem\u00e1s, no es mala idea cultivar <strong>con bombillas de bajo consumo<\/strong>. Es cierto que con estas l\u00e1mparas no obtendremos una producci\u00f3n tan grande como con otras, pero mantendremos la <strong>calidad<\/strong> de nuestra cosecha y no fastidiaremos el cultivo durante estos meses.<\/p>\n<h2><strong>Sacar el calor del indoor<\/strong><\/h2>\n<p>Podemos usar dos m\u00e9todos para extraer el calor del cuarto de cultivo, bien con el aire acondicionado o bien con un <a href=\"https:\/\/cogolandia.com\/producto\/extractor-centro-blauberg-2-velocidades\/\">extractor<\/a>.<\/p>\n<p>El <strong>segundo<\/strong>, mucho <strong>m\u00e1s econ\u00f3mico<\/strong> que el primero. Eso s\u00ed, el sistema de extracci\u00f3n s\u00f3lo sirve para <strong>cultivos relativamente peque\u00f1os<\/strong>.<\/p>\n<p>Si optamos por el aire acondicionado, lo utilizaremos <strong>durante todo el d\u00eda.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El verano no es bienvenido por mucha gente, y menos por los cultivadores de marihuana en interior. Cultivar marihuana en verano es toda una odisea, ya que es el per\u00edodo\u00a0m\u00e1s delicado para las plantas.\u00a0Un cultivo indoor es todo un reto para cualquier cultivador. El calor de las l\u00e1mparas y de los aparatos, unidos a las [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":20088,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-20086","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cannabis"],"_links":{"self":[{"href":"https:\/\/cogolandia.com\/blog\/wp-json\/wp\/v2\/posts\/20086","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cogolandia.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cogolandia.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cogolandia.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cogolandia.com\/blog\/wp-json\/wp\/v2\/comments?post=20086"}],"version-history":[{"count":0,"href":"https:\/\/cogolandia.com\/blog\/wp-json\/wp\/v2\/posts\/20086\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cogolandia.com\/blog\/wp-json\/wp\/v2\/media\/20088"}],"wp:attachment":[{"href":"https:\/\/cogolandia.com\/blog\/wp-json\/wp\/v2\/media?parent=20086"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cogolandia.com\/blog\/wp-json\/wp\/v2\/categories?post=20086"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cogolandia.com\/blog\/wp-json\/wp\/v2\/tags?post=20086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}