{"id":22279,"date":"2016-11-14T11:30:52","date_gmt":"2016-11-14T10:30:52","guid":{"rendered":"https:\/\/cogolandia.com\/?p=22279"},"modified":"2016-11-14T11:30:52","modified_gmt":"2016-11-14T10:30:52","slug":"marihuana-y-diabetes","status":"publish","type":"post","link":"https:\/\/cogolandia.com\/blog\/cannabis\/marihuana-y-diabetes\/","title":{"rendered":"Marihuana y diabetes. Alivio de los dolores"},"content":{"rendered":"<p>Como ya hemos comentado en anteriores art\u00edculos, y apoy\u00e1ndonos en varios estudios, la marihuana tiene la capacidad de reducir dolores, mejorar el estado de \u00e1nimo y aumentar el apetito en personas que sufren diversas enfermedades. En este post, vamos a centrarnos en la relaci\u00f3n que existe entre la\u00a0<strong>marihuana y diabetes<\/strong>.<\/p>\n<p>Desde siempre, el consumo de cannabis ha estado ligado a debate y pol\u00e9mica. Por una parte, existe un sector de la poblaci\u00f3n que defiende el uso de la marihuana medicinal como sustitutivo a los medicamentos. Por la otra, est\u00e1n los detractores, que alegan que el consumo de cannabis induce al consumo de otras drogas.<\/p>\n<p>De cualquier manera, los enfermos que recurren a los beneficios de la marihuana, han notado como <strong>parte de sus dolores se han disminuido<\/strong>.<\/p>\n<p>Por el momento, no existe ninguna investigaci\u00f3n que afirme que el uso de la marihuana trata la diabetes. Sin embargo, s\u00ed que se han realizado estudios en los que se confirma que los cannabinoides ayudan a aliviar algunos s\u00edntomas.<\/p>\n<p>Un estudio ejecutado en 2004, afirm\u00f3 que los ratones, a los que les administraron un activador de los receptores cannabinoides, redujeron el dolor relacionado con la diabetes. En este sentido, se confirm\u00f3 la relaci\u00f3n existente entre la marihuana y la diabetes.<\/p>\n<p><a href=\"https:\/\/cogolandia.com\/wp-content\/uploads\/2016\/11\/marihuana-y-diabetes.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-22280 aligncenter\" src=\"https:\/\/cogolandia.com\/wp-content\/uploads\/2016\/11\/marihuana-y-diabetes.jpg\" alt=\"marihuana y diabetes\" width=\"392\" height=\"262\" srcset=\"https:\/\/cogolandia.com\/blog\/wp-content\/uploads\/2016\/11\/marihuana-y-diabetes.jpg 640w, https:\/\/cogolandia.com\/blog\/wp-content\/uploads\/2016\/11\/marihuana-y-diabetes-300x201.jpg 300w\" sizes=\"(max-width: 392px) 100vw, 392px\" \/><\/a><\/p>\n<p>Es cierto que estas investigaciones se han centrado en animales. Sin embargo, estudios de los \u00faltimos a\u00f1os han evidenciado los posibles beneficios para reducir los dolores de los diab\u00e9ticos.<\/p>\n<h2>Marihuana y diabetes. Beneficios:<\/h2>\n<ol>\n<li>Alivia la inflamaci\u00f3n de las arterias<\/li>\n<li>Disminuye el dolor de la neuropat\u00eda<\/li>\n<li>Equilibra la cantidad de az\u00facar en la sangre<\/li>\n<li>Reduce el riesgo de posibles enfermedades de coraz\u00f3n<\/li>\n<li>Mejora la circulaci\u00f3n<\/li>\n<li>Relaja los m\u00fasculos y el dolor gastrointestinal<\/li>\n<\/ol>\n<p>El uso de la marihuana en aceite tambi\u00e9n previene el hormigueo en las manos y en los pies.<\/p>\n<p>De todas formas, es cierto que todav\u00eda necesitamos mayor investigaci\u00f3n sobre los beneficios que aporta la marihuana y la relaci\u00f3n de esta con enfermedades como la diabetes o el c\u00e1ncer.<\/p>\n<p>Si los cient\u00edficos certificasen estos beneficios, se podr\u00edan crear tratamientos basados en estos activos. \u00a0Con ello, muchos s\u00edntomas se aliviar\u00edan con el consumo de marihuana, siempre bajo control cl\u00ednico.<\/p>\n<p>Sin embargo, parece que a\u00fan estamos a a\u00f1os luz de que esto pueda ocurrir. A la vista est\u00e1 que ni los pol\u00edticos ni las grandes farmac\u00e9uticas est\u00e1n por la labor de debatir el caso. No vaya a ser que se les corte el chorro\u2026<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como ya hemos comentado en anteriores art\u00edculos, y apoy\u00e1ndonos en varios estudios, la marihuana tiene la capacidad de reducir dolores, mejorar el estado de \u00e1nimo y aumentar el apetito en personas que sufren diversas enfermedades. En este post, vamos a centrarnos en la relaci\u00f3n que existe entre la\u00a0marihuana y diabetes. Desde siempre, el consumo de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":22282,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-22279","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cannabis"],"_links":{"self":[{"href":"https:\/\/cogolandia.com\/blog\/wp-json\/wp\/v2\/posts\/22279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cogolandia.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cogolandia.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cogolandia.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cogolandia.com\/blog\/wp-json\/wp\/v2\/comments?post=22279"}],"version-history":[{"count":0,"href":"https:\/\/cogolandia.com\/blog\/wp-json\/wp\/v2\/posts\/22279\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cogolandia.com\/blog\/wp-json\/wp\/v2\/media\/22282"}],"wp:attachment":[{"href":"https:\/\/cogolandia.com\/blog\/wp-json\/wp\/v2\/media?parent=22279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cogolandia.com\/blog\/wp-json\/wp\/v2\/categories?post=22279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cogolandia.com\/blog\/wp-json\/wp\/v2\/tags?post=22279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}